{"id":66034,"date":"2024-05-14T13:58:43","date_gmt":"2024-05-14T12:58:43","guid":{"rendered":"https:\/\/www.whistlelink.com\/?post_type=blog&#038;p=66034"},"modified":"2024-05-14T14:42:52","modified_gmt":"2024-05-14T13:42:52","slug":"la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression","status":"publish","type":"blog","link":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/","title":{"rendered":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement menace la d\u00e9mocratie et la libert\u00e9 d&rsquo;expression"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La d\u00e9nonciation est un aspect crucial de la d\u00e9mocratie. Elle permet aux individus de r\u00e9v\u00e9ler la corruption et les actes r\u00e9pr\u00e9hensibles au sein des institutions. Cependant, les r\u00e9cents d\u00e9veloppements en Croatie ont suscit\u00e9 la controverse et soulev\u00e9 des inqui\u00e9tudes quant \u00e0 l&rsquo;\u00e9touffement des d\u00e9nonciateurs et \u00e0 l&rsquo;impact sur le journalisme. L&rsquo;adoption d&rsquo;une loi controvers\u00e9e visant les d\u00e9nonciateurs en Croatie a d\u00e9clench\u00e9 un d\u00e9bat houleux. Les critiques d\u00e9noncent la l\u00e9gislation comme une menace pour la d\u00e9mocratie et la libert\u00e9 des m\u00e9dias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-croatie-est-devenue-le-neuvieme-pays-a-transposer-la-directive-sur-les-lanceurs-d-alerte-en-2022\">La Croatie est devenue le neuvi\u00e8me pays \u00e0 transposer la directive sur les lanceurs d&rsquo;alerte en 2022<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La loi sur la protection des lanceurs d&rsquo;alerte a \u00e9t\u00e9 adopt\u00e9e en Croatie le 23 avril 2022, rempla\u00e7ant la pr\u00e9c\u00e9dent loi en vigueur depuis 2019. La nouvelle loi est con\u00e7ue pour assurer une protection efficace des lanceurs d&rsquo;alerte. La loi am\u00e9liorera \u00e9galement le syst\u00e8me de signalement des irr\u00e9gularit\u00e9s, en alignant la l\u00e9gislation croate sur la directive europ\u00e9enne relative \u00e0 la d\u00e9nonciation.<br><br>La loi couvre divers aspects tels que les m\u00e9canismes de signalement, les droits et obligations des lanceurs d&rsquo;alerte, les mesures de protection et les responsabilit\u00e9s des organisations et des employeurs. Elle propose des d\u00e9finitions plus claires et des proc\u00e9dures sp\u00e9cifiques. La loi croate sur la protection des d\u00e9nonciateurs semble remplir son objectif premier, qui est de prot\u00e9ger efficacement les d\u00e9nonciateurs, du moins sur le papier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-modifications-controversees-de-la-protection-des-denonciateurs-dans-la-loi-lex-ap\">Modifications controvers\u00e9es de la protection des d\u00e9nonciateurs dans la loi \u00ab\u00a0Lex AP<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, la nouvelle loi introduite en mars 2024, surnomm\u00e9e \u00ab\u00a0Lex AP\u00a0\u00bb d&rsquo;apr\u00e8s le Premier ministre Andrej Plenkovic, rend ill\u00e9gale la divulgation aux journalistes d&rsquo;informations provenant d&rsquo;enqu\u00eates polici\u00e8res. Les d\u00e9nonciateurs s&rsquo;exposent d\u00e9sormais \u00e0 des sanctions s\u00e9v\u00e8res, y compris l&#8217;emprisonnement, pour avoir expos\u00e9 la corruption et les fautes professionnelles. Le gouvernement justifie cette loi par la n\u00e9cessit\u00e9 de prot\u00e9ger la pr\u00e9somption d&rsquo;innocence et les droits personnels des personnes faisant l&rsquo;objet d&rsquo;une enqu\u00eate. N\u00e9anmoins, les critiques affirment que l&rsquo;intention r\u00e9elle est de supprimer la libert\u00e9 d&rsquo;expression, de couvrir la corruption politique et de saper la libert\u00e9 des m\u00e9dias.<br><br>La F\u00e9d\u00e9ration europ\u00e9enne des journalistes et<a href=\"https:\/\/www.hnd.hr\/eng\/open-letter-from-cja-to-citizens-about-the-dangers-of-amendments-to-the-criminal-code\" target=\"_blank\" rel=\"noreferrer noopener\"> l&rsquo;Association des journalistes croates ont exprim\u00e9 de vives inqui\u00e9tudes quant aux implications de la nouvelle loi<\/a>. Il estime que la l\u00e9gislation cherche \u00e0 intimider les journalistes et \u00e0 restreindre leur capacit\u00e9 \u00e0 demander des comptes \u00e0 ceux qui sont au pouvoir. En criminalisant les d\u00e9nonciateurs et en soumettant les journalistes \u00e0 des r\u00e9percussions, la loi repr\u00e9sente une menace importante pour le journalisme ind\u00e9pendant et la transparence.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-remise-en-question-du-moment-choisi-pour-l-adoption-de-la-loi\">Remise en question du moment choisi pour l&rsquo;adoption de la loi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le moment choisi pour l&rsquo;adoption de la loi, juste avant la dissolution du parlement et les prochaines \u00e9lections, a suscit\u00e9 des soup\u00e7ons quant aux motivations du gouvernement. Les politiciens de l&rsquo;opposition et les m\u00e9dias qui critiquent le gouvernement ont accus\u00e9 le premier ministre Plenkovic. Il utilise la loi pour faire taire les dissidents et prot\u00e9ger les pratiques corrompues au sein de son administration. La pr\u00e9cipitation avec laquelle la l\u00e9gislation a \u00e9t\u00e9 adopt\u00e9e, en d\u00e9pit de l&rsquo;opposition et des protestations g\u00e9n\u00e9ralis\u00e9es, ne fait qu&rsquo;alimenter les inqui\u00e9tudes concernant l&rsquo;\u00e9rosion des valeurs d\u00e9mocratiques et la consolidation du pouvoir entre les mains de la coalition au pouvoir.<br><br>Les parall\u00e8les \u00e9tablis entre le premier ministre Plenkovic et des dirigeants autoritaires tels que Viktor Orban mettent en lumi\u00e8re des pr\u00e9occupations plus g\u00e9n\u00e9rales quant \u00e0 l&rsquo;\u00e9tat de la d\u00e9mocratie en Croatie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-croatie-a-fait-l-objet-de-critiques-internationales\">La Croatie a fait l&rsquo;objet de critiques internationales<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les critiques du Conseil de l&rsquo;Europe concernant la nouvelle loi sur les d\u00e9nonciateurs et son impact potentiel sur la libert\u00e9 de la presse soulignent l&rsquo;inqui\u00e9tude de la communaut\u00e9 internationale face \u00e0 l&rsquo;\u00e9rosion des normes d\u00e9mocratiques en Croatie. La menace imminente d&rsquo;un paysage m\u00e9diatique contr\u00f4l\u00e9 par l&rsquo;\u00c9tat et de la suppression du journalisme ind\u00e9pendant fait craindre un glissement possible vers l&rsquo;autoritarisme et la violation des libert\u00e9s civiles.<br><br>&nbsp;Alors que la Croatie se pr\u00e9pare pour les \u00e9lections parlementaires et les \u00e9lections europ\u00e9ennes, le paysage politique en cours pr\u00e9sente un moment critique pour l&rsquo;avenir de la d\u00e9mocratie dans le pays. La d\u00e9cision du pr\u00e9sident Zoran Milanovic de se pr\u00e9senter au poste de premier ministre en tant que candidat de l&rsquo;opposition signale un changement potentiel dans la dynamique du pouvoir et peut-\u00eatre un regain d&rsquo;int\u00e9r\u00eat pour le respect des valeurs d\u00e9mocratiques et la transparence.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-defis-pour-la-democratie-et-l-integrite-des-medias\">D\u00e9fis pour la d\u00e9mocratie et l&rsquo;int\u00e9grit\u00e9 des m\u00e9dias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La loi controvers\u00e9e sur les d\u00e9nonciateurs en Croatie repr\u00e9sente une menace importante pour la d\u00e9mocratie, la libert\u00e9 des m\u00e9dias et la transparence. L&rsquo;\u00e9touffement des d\u00e9nonciateurs et la criminalisation des journalistes compromettent le r\u00f4le essentiel de la presse pour demander des comptes au pouvoir et d\u00e9noncer la corruption. Alors que la Croatie traverse un climat politique difficile, la protection des d\u00e9nonciateurs et la pr\u00e9servation d&rsquo;une presse ind\u00e9pendante sont des piliers essentiels d&rsquo;une d\u00e9mocratie saine.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Int\u00e9ress\u00e9 par Whistlelink? <a href=\"https:\/\/www.whistlelink.com\/fr\/produit\/\" target=\"_blank\" rel=\"noreferrer noopener\">Visitez notre site web<\/a> pour en savoir plus sur la loi sur les lanceurs d\u2019alerte en France, en Belgique ou au Luxembourg. Whistlelink peut vous aider \u00e0 vous mettre en conformit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous souhaitez discuter d&rsquo;une solution de lancement d\u2019alerte pour votre organisation ? <a href=\"https:\/\/www.whistlelink.com\/fr\/reserver-une-demo\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9server une d\u00e9mo gratuite<\/a> de notre syst\u00e8me !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9nonciation est un aspect crucial de la d\u00e9mocratie. Elle permet aux individus de r\u00e9v\u00e9ler la corruption et les actes r\u00e9pr\u00e9hensibles au sein des institutions. Cependant, les r\u00e9cents d\u00e9veloppements en Croatie ont suscit\u00e9 la controverse et soulev\u00e9 des inqui\u00e9tudes quant \u00e0 l&rsquo;\u00e9touffement des d\u00e9nonciateurs et \u00e0 l&rsquo;impact sur le journalisme. L&rsquo;adoption d&rsquo;une loi controvers\u00e9e visant [&hellip;]<\/p>\n","protected":false},"featured_media":66024,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"loi croate sur le signalement","_yoast_wpseo_title":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement %%sep%% %%sitename%%","_yoast_wpseo_metadesc":"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie."},"blog-category":[208],"class_list":["post-66034","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","blog-category-articles-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement - Whistlelink<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement menace la d\u00e9mocratie et la libert\u00e9 d&#039;expression\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/\" \/>\n<meta property=\"og:site_name\" content=\"Whistlelink\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/whistlelink\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-14T13:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2024\/04\/Croatias-controversial-whistleblower-reform.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/\",\"name\":\"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement - Whistlelink\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Croatias-controversial-whistleblower-reform.png\",\"datePublished\":\"2024-05-14T12:58:43+00:00\",\"dateModified\":\"2024-05-14T13:42:52+00:00\",\"description\":\"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Croatias-controversial-whistleblower-reform.png\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Croatias-controversial-whistleblower-reform.png\",\"width\":1200,\"height\":628,\"caption\":\"The controversial reform of the whistleblower law in Croatia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/home-whistlelink-com-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement menace la d\u00e9mocratie et la libert\u00e9 d&#8217;expression\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/\",\"name\":\"Whistlelink\",\"description\":\"Un fournisseur de confiance de solutions s\u00e9curis\u00e9es de signalement d'alertes.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/#organization\",\"name\":\"Whistlelink\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"width\":1200,\"height\":1200,\"caption\":\"Whistlelink\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/whistlelink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/whistlelink\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Whistlelink\"],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"name\":\"Annelie Demred\",\"contactType\":\"Territory Manager (CEO Whistlelink)\",\"telephone\":\"+46706838288\",\"email\":\"annelie.demred@whistlelink.com\",\"areaServed\":[\"EU\",\"Rest of the World\"],\"availableLanguage\":[\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Philipp Garz\",\"contactType\":\"Territory Manager\",\"telephone\":\"+498001816067\",\"email\":\"philipp.garz@whistlelink.com\",\"areaServed\":[\"Germany\",\"Austria\",\"Switzerland\",\"Sweden\"],\"availableLanguage\":[\"German\",\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Maria Boboc\",\"contactType\":\"Territory Manager\",\"telephone\":\"+34900752496\",\"email\":\"maria.boboc@whistlelink.com\",\"areaServed\":[\"United States\",\"Latin America\",\"Spain\",\"Romania\",\"Portugal\",\"Bulgaria\"],\"availableLanguage\":[\"Spanish\",\"Romanian\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Camilla Corsini\",\"contactType\":\"Territory Manager\",\"telephone\":\"+39800934277\",\"email\":\"camilla.corsini@whistlelink.com\",\"areaServed\":[\"Italy\",\"France\",\"Belgium\",\"Luxembourg\",\"Slovenia\",\"Serbia\",\"Croatia\",\"Greece\"],\"availableLanguage\":[\"Italian\",\"French\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Urszula Garbicz-Bry\u015b\",\"contactType\":\"Territory Manager\",\"telephone\":\"+48800005274\",\"email\":\"urszula.brys@whistlelink.com\",\"areaServed\":[\"Poland\",\"Czech Republic\",\"Slovakia\",\"Hungary\",\"Estonia\",\"Latvia\",\"Lithuania\"],\"availableLanguage\":[\"Polish\",\"English\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement - Whistlelink","description":"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement menace la d\u00e9mocratie et la libert\u00e9 d'expression","og_description":"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.","og_url":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/","og_site_name":"Whistlelink","article_publisher":"https:\/\/www.facebook.com\/whistlelink\/","article_modified_time":"2024-05-14T13:42:52+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2024\/04\/Croatias-controversial-whistleblower-reform.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/","url":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/","name":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement - Whistlelink","isPartOf":{"@id":"https:\/\/www.whistlelink.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/#primaryimage"},"image":{"@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/#primaryimage"},"thumbnailUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2024\/04\/Croatias-controversial-whistleblower-reform.png","datePublished":"2024-05-14T12:58:43+00:00","dateModified":"2024-05-14T13:42:52+00:00","description":"D\u00e9couvrez la controverse qui entoure la loi croate sur le signalement. Les changements r\u00e9cents pourraient avoir un impact sur la d\u00e9mocratie.","breadcrumb":{"@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/#primaryimage","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2024\/04\/Croatias-controversial-whistleblower-reform.png","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2024\/04\/Croatias-controversial-whistleblower-reform.png","width":1200,"height":628,"caption":"The controversial reform of the whistleblower law in Croatia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.whistlelink.com\/fr\/blog\/la-reforme-controversee-de-la-loi-croate-sur-le-signalement-menace-la-democratie-et-la-liberte-dexpression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.whistlelink.com\/fr\/home-whistlelink-com-fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.whistlelink.com\/fr\/blog\/"},{"@type":"ListItem","position":3,"name":"La r\u00e9forme controvers\u00e9e de la loi croate sur le signalement menace la d\u00e9mocratie et la libert\u00e9 d&#8217;expression"}]},{"@type":"WebSite","@id":"https:\/\/www.whistlelink.com\/fr\/#website","url":"https:\/\/www.whistlelink.com\/fr\/","name":"Whistlelink","description":"Un fournisseur de confiance de solutions s\u00e9curis\u00e9es de signalement d'alertes.","publisher":{"@id":"https:\/\/www.whistlelink.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.whistlelink.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.whistlelink.com\/#organization","name":"Whistlelink","url":"https:\/\/www.whistlelink.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.whistlelink.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","width":1200,"height":1200,"caption":"Whistlelink"},"image":{"@id":"https:\/\/www.whistlelink.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/whistlelink\/","https:\/\/www.linkedin.com\/company\/whistlelink\/","https:\/\/www.youtube.com\/@Whistlelink"],"contactPoint":[{"@type":"ContactPoint","name":"Annelie Demred","contactType":"Territory Manager (CEO Whistlelink)","telephone":"+46706838288","email":"annelie.demred@whistlelink.com","areaServed":["EU","Rest of the World"],"availableLanguage":["Swedish","English"]},{"@type":"ContactPoint","name":"Philipp Garz","contactType":"Territory Manager","telephone":"+498001816067","email":"philipp.garz@whistlelink.com","areaServed":["Germany","Austria","Switzerland","Sweden"],"availableLanguage":["German","Swedish","English"]},{"@type":"ContactPoint","name":"Maria Boboc","contactType":"Territory Manager","telephone":"+34900752496","email":"maria.boboc@whistlelink.com","areaServed":["United States","Latin America","Spain","Romania","Portugal","Bulgaria"],"availableLanguage":["Spanish","Romanian","English"]},{"@type":"ContactPoint","name":"Camilla Corsini","contactType":"Territory Manager","telephone":"+39800934277","email":"camilla.corsini@whistlelink.com","areaServed":["Italy","France","Belgium","Luxembourg","Slovenia","Serbia","Croatia","Greece"],"availableLanguage":["Italian","French","English"]},{"@type":"ContactPoint","name":"Urszula Garbicz-Bry\u015b","contactType":"Territory Manager","telephone":"+48800005274","email":"urszula.brys@whistlelink.com","areaServed":["Poland","Czech Republic","Slovakia","Hungary","Estonia","Latvia","Lithuania"],"availableLanguage":["Polish","English"]}]}]}},"_links":{"self":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/blog\/66034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":4,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/blog\/66034\/revisions"}],"predecessor-version":[{"id":67407,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/blog\/66034\/revisions\/67407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/media\/66024"}],"wp:attachment":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/media?parent=66034"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/blog-category?post=66034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}