{"id":23614,"date":"2022-01-19T10:26:59","date_gmt":"2022-01-19T09:26:59","guid":{"rendered":"https:\/\/www.whistlelink.com\/?page_id=23614"},"modified":"2026-09-01T10:43:37","modified_gmt":"2026-09-01T09:43:37","slug":"se-mettre-en-conformite-directive-eu-lanceurs-alerte","status":"publish","type":"page","link":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/","title":{"rendered":"Assurez votre conformit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23614\" class=\"elementor elementor-23614 elementor-19819\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-632017a4 e-con-full e-flex e-con e-parent\" data-id=\"632017a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5c1f65a1 e-con-full e-flex e-con e-child\" data-id=\"5c1f65a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b29f5d elementor-widget elementor-widget-jet-headline\" data-id=\"1b29f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Directive sur le lancement d'alerte<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Comment se mettre en conformit\u00e9 avec <br>les lois sur le lancement d'alertes ?<\/span><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c139606 e-flex e-con-boxed e-con e-parent\" data-id=\"7c139606\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3f23306a e-con-full e-flex e-con e-child\" data-id=\"3f23306a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6385d5e5 e-con-full e-flex e-con e-child\" data-id=\"6385d5e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-770356d5 e-con-full e-flex e-con e-child\" data-id=\"770356d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-130ea4f4 elementor-hidden-widescreen elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile elementor-hidden-desktop e-flex e-con-boxed e-con e-child\" data-id=\"130ea4f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a604dc elementor-widget elementor-widget-template\" data-id=\"6a604dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"62586\" class=\"elementor elementor-62586 elementor-62543 elementor-62543\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b67229c e-flex e-con-boxed e-con e-child\" data-id=\"4b67229c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fba6039 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7fba6039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.whistlelink.com\/whistlelink-whitepapers\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"T\u00e9l\u00e9chargez notre livre blanc gratuit\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.whistlelink.com\/whistlelink-whitepapers\/\" >\n\t\t\t\t\t\t\tT\u00e9l\u00e9chargez notre livre blanc gratuit\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tComment se conformer \u00e0 la loi sur le lancement d'alerte\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3344d919 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3344d919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b66ff7c elementor-widget elementor-widget-text-editor\" data-id=\"b66ff7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">La directive europ\u00e9enne sur le lancement d&rsquo;alerte (2019\/1937) a \u00e9t\u00e9 introduite pour prot\u00e9ger les personnes qui signalent des fautes professionnelles. Cette r\u00e9glementation exige que les organisations mettent en place des syst\u00e8mes de signalement s\u00e9curis\u00e9s et confidentiels qui prot\u00e8gent les lanceurs d&rsquo;alerte contre les repr\u00e9sailles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5916562 elementor-widget elementor-widget-jet-headline\" data-id=\"5916562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Exigences de la directive<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Impact de la directive europ\u00e9enne sur le lancement d'alerte pour les organisations<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bbad26 elementor-widget elementor-widget-text-editor\" data-id=\"0bbad26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Les organisations employant au moins 50 personnes et les municipalit\u00e9s de plus de 10 000 habitants sont tenues de mettre en place des syst\u00e8mes de signalement s\u00fbrs et efficaces. Ces syst\u00e8mes doivent \u00eatre con\u00e7us pour garantir la s\u00e9curit\u00e9 et la confidentialit\u00e9 des lanceurs d&rsquo;alerte, tout en respectant les obligations l\u00e9gales.<\/p><p data-pm-slice=\"1 1 []\">Pour \u00eatre conformes \u00e0 la directive, les canaux de signalement doivent<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dbe4b1e e-con-full e-flex e-con e-child\" data-id=\"dbe4b1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05ca17b e-flex e-con-boxed e-con e-child\" data-id=\"05ca17b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c268f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a3c268f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c95eb6d elementor-widget elementor-widget-text-editor\" data-id=\"c95eb6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00eatre s\u00e9curis\u00e9s<\/p><p>garantir la confidentialit\u00e9<\/p><p>avoir un propri\u00e9taire d\u00e9sign\u00e9<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-049b90d e-flex e-con-boxed e-con e-child\" data-id=\"049b90d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b27eb8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0b27eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a1f25 elementor-widget elementor-widget-text-editor\" data-id=\"22a1f25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>respecter les d\u00e9lais<\/p><p>respecter les lignes directrices du RGPD<\/p><p>permettre des rapports \u00e9crits et\/ou verbaux<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9704140 e-con-full e-flex e-con e-child\" data-id=\"9704140\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d4f1e2c e-con-full e-flex e-con e-child\" data-id=\"d4f1e2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33751ee elementor-widget elementor-widget-jet-headline\" data-id=\"33751ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">D\u00e9tails importants<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Principaux aspects de la directive sur le lancement d'alerte<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53c0e76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"53c0e76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0725f8 elementor-widget elementor-widget-heading\" data-id=\"a0725f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qui peut signaler une faute professionnelle ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8cbb23 elementor-widget elementor-widget-text-editor\" data-id=\"e8cbb23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 3 []\">Toute personne ayant connaissance d&rsquo;une faute professionnelle peut d\u00e9poser un rapport. La protection s&rsquo;\u00e9tend au-del\u00e0 des employ\u00e9s actuels pour inclure les anciens employ\u00e9s, les candidats \u00e0 l&#8217;emploi, les sous-traitants et les fournisseurs, ainsi que les personnes qui soutiennent le d\u00e9nonciateur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04b9ae9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"04b9ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a036ee9 elementor-widget elementor-widget-heading\" data-id=\"a036ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Quels types de fautes peuvent \u00eatre signal\u00e9s ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6e44bb elementor-widget elementor-widget-text-editor\" data-id=\"a6e44bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les rapports de lancements d&rsquo;alerte peuvent porter sur des violations de la l\u00e9gislation de l&rsquo;UE li\u00e9es \u00e0 divers probl\u00e8mes, y compris, mais sans s&rsquo;y limiter, les suivants<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38cdf73 elementor-widget elementor-widget-text-editor\" data-id=\"38cdf73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul data-spread=\"false\" data-pm-slice=\"3 3 []\"><li><p>le blanchiment d&rsquo;argent et la fraude fiscale<\/p><\/li><li><p>la s\u00e9curit\u00e9 des produits et des transports<\/p><\/li><li><p>la protection des donn\u00e9es et de la vie priv\u00e9e<\/p><\/li><li><p>les probl\u00e8mes de sant\u00e9 publique<\/p><\/li><li><p>les atteintes au bien-\u00eatre des animaux<\/p><\/li><li><p>les infractions en mati\u00e8re de protection de l&rsquo;environnement<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce73e8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dce73e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98f476f elementor-widget elementor-widget-heading\" data-id=\"98f476f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La protection des lanceurs d'alerte contre les repr\u00e9sailles<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd45553 elementor-widget elementor-widget-text-editor\" data-id=\"dd45553\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Les lanceurs d&rsquo;alerte sont l\u00e9galement prot\u00e9g\u00e9s contre toute forme de repr\u00e9sailles lorsqu&rsquo;ils soumettent un rapport par l&rsquo;interm\u00e9diaire du canal de signalement d\u00e9sign\u00e9. Pour b\u00e9n\u00e9ficier de cette protection, le lanceur d&rsquo;alerte doit \u00eatre raisonnablement convaincu de la v\u00e9racit\u00e9 des informations qu&rsquo;il fournit au moment du signalement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef6dd86 e-con-full e-flex e-con e-child\" data-id=\"ef6dd86\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5f8fa3f e-con-full e-flex e-con e-child\" data-id=\"5f8fa3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcd6ace elementor-widget elementor-widget-jet-headline\" data-id=\"fcd6ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Canaux de signalement internes<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Sanctions en cas de non-respect des r\u00e8gles<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0a2cbb elementor-widget elementor-widget-text-editor\" data-id=\"e0a2cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bien que la directive europ\u00e9enne sur le lancement d&rsquo;alerte n&rsquo;\u00e9tablisse pas de sanctions minimales sp\u00e9cifiques, elle exige des <a href=\"https:\/\/www.whistlelink.com\/fr\/lois-nationales-sur-les-lanceurs-dalerte-dans-lue\/\" target=\"_blank\" rel=\"noopener\">\u00e9tats membres qu&rsquo;ils mettent en \u0153uvre des lois nationales<\/a> imposant des sanctions aux organisations qui :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1fdace e-con-full e-flex e-con e-child\" data-id=\"b1fdace\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ae690e9 e-con-full e-flex e-con e-child\" data-id=\"ae690e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25add27 elementor-widget elementor-widget-image\" data-id=\"25add27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png\" class=\"attachment-large size-large wp-image-19984\" alt=\"\" srcset=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png 600w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane-300x300.png 300w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane-150x150.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84aed41 e-con-full e-flex e-con e-child\" data-id=\"84aed41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5469fde elementor-widget elementor-widget-text-editor\" data-id=\"5469fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>entravent ou emp\u00eachent les d\u00e9nonciations en d\u00e9courageant ou en bloquant les rapports.<\/li><li><p>violent la confidentialit\u00e9 en divulguant l&rsquo;identit\u00e9 d&rsquo;un d\u00e9nonciateur sans son consentement.<\/p><\/li><li><p>exercent des repr\u00e9sailles contre les d\u00e9nonciateurs en les licenciant, en les harcelant ou en les discriminant.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eb084a elementor-widget elementor-widget-text-editor\" data-id=\"5eb084a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le non-respect des lois nationales sur la protection des lanceurs d&rsquo;alerte peut entra\u00eener des sanctions financi\u00e8res importantes, des poursuites judiciaires et une atteinte \u00e0 la r\u00e9putation des organisations. Il est essentiel de mettre en place des canaux de signalement internes et des mesures de protection appropri\u00e9s pour assurer la conformit\u00e9 et maintenir la confiance au sein de votre organisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-852ca5d e-con-full e-flex e-con e-child\" data-id=\"852ca5d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d89f4ad elementor-widget elementor-widget-jet-headline\" data-id=\"d89f4ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Comment se conformer<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">6 \u00e9tapes essentielles pour r\u00e9pondre aux exigences en mati\u00e8re de lancement d'alerte<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a27818 elementor-widget elementor-widget-text-editor\" data-id=\"2a27818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Suivez ces \u00e9tapes pour vous assurer que votre organisation se conforme \u00e0 la directive sur le lancement d&rsquo;alerte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d342245 e-con-full e-flex e-con e-child\" data-id=\"d342245\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2e4b1e0 e-flex e-con-boxed e-con e-child\" data-id=\"2e4b1e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-783ead6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"783ead6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd472e elementor-widget elementor-widget-heading\" data-id=\"bcd472e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9pondez en temps utile<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a9cea2 elementor-widget elementor-widget-text-editor\" data-id=\"8a9cea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mettez en place une proc\u00e9dure permettant d&rsquo;accuser r\u00e9ception du rapport dans les sept jours et de fournir un retour d&rsquo;information au lanceur d&rsquo;alerte dans les trois mois.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73c1572 e-flex e-con-boxed e-con e-child\" data-id=\"73c1572\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e8836 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e8e8836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48aced8 elementor-widget elementor-widget-heading\" data-id=\"48aced8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alignez les proc\u00e9dures de lancement d'alerte sur le RGPD<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4e061 elementor-widget elementor-widget-text-editor\" data-id=\"da4e061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 3 []\">Continuez \u00e0 vous conformer aux exigences du RGPD en g\u00e9rant soigneusement les donn\u00e9es personnelles et en veillant \u00e0 ce que les donn\u00e9es soient stock\u00e9es en toute s\u00e9curit\u00e9 au sein de l&rsquo;UE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6747c0ef e-con-full e-flex e-con e-child\" data-id=\"6747c0ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25bd7bcd e-flex e-con-boxed e-con e-child\" data-id=\"25bd7bcd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-384b1a4f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"384b1a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-848e1a2 elementor-widget elementor-widget-heading\" data-id=\"848e1a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mettez en place des canaux de signalement s\u00e9curis\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92cbffa elementor-widget elementor-widget-text-editor\" data-id=\"92cbffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Mettez en place des canaux de signalement qui garantissent la confidentialit\u00e9 et prot\u00e8gent l&rsquo;identit\u00e9 des d\u00e9nonciateurs et de toute personne cit\u00e9e dans les rapports. S\u00e9curisez votre syst\u00e8me contre tout acc\u00e8s non autoris\u00e9 et conservez des enregistrements s\u00fbrs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19914953 e-flex e-con-boxed e-con e-child\" data-id=\"19914953\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f2ca34a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1f2ca34a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7276e elementor-widget elementor-widget-heading\" data-id=\"fb7276e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Proposez plusieurs options de signalement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e050eb9 elementor-widget elementor-widget-text-editor\" data-id=\"e050eb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proposez des options de signalement flexibles. Acceptez les rapports \u00e9crits via une plateforme en ligne, les rapports oraux par t\u00e9l\u00e9phone ou messages vocaux, et proposez des r\u00e9unions personnelles sur demande.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7fda2c5 e-con-full e-flex e-con e-child\" data-id=\"7fda2c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0d42f59 e-flex e-con-boxed e-con e-child\" data-id=\"0d42f59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25e55b9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"25e55b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2a535 elementor-widget elementor-widget-heading\" data-id=\"7c2a535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9signez un responsable<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-449c629 elementor-widget elementor-widget-text-editor\" data-id=\"449c629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 3 []\">D\u00e9signez une personne ou un service qualifi\u00e9 pour traiter les signalements entrants. Ses responsabilit\u00e9s doivent inclure la gestion du processus de signalement, le maintien d&rsquo;une communication continue avec le lanceur d&rsquo;alerte et la fourniture d&rsquo;un retour d&rsquo;information en temps utile.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8525a73 e-flex e-con-boxed e-con e-child\" data-id=\"8525a73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebe7b0a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ebe7b0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7fa990 elementor-widget elementor-widget-heading\" data-id=\"a7fa990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rendez les canaux de signalement accessibles<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0501dfa elementor-widget elementor-widget-text-editor\" data-id=\"0501dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Veillez \u00e0 ce que vos canaux de signalement soient facilement accessibles \u00e0 tous les employ\u00e9s et \u00e9tendez l&rsquo;acc\u00e8s aux parties prenantes externes telles que les fournisseurs, les sous-traitants, les actionnaires, les stagiaires et les candidats \u00e0 l&#8217;emploi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7e149c e-con-full e-flex e-con e-child\" data-id=\"e7e149c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-170c3eb elementor-position-inline-start elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"170c3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:serif=\"http:\/\/www.serif.com\/\" width=\"100%\" height=\"100%\" viewBox=\"0 0 4375 4121\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:2;\"><g><path d=\"M3446.07,0l-2514.82,0c-512.173,0 -931.245,419.072 -931.245,931.245l-0,2258.34c-0,512.199 419.072,931.244 931.245,931.244l2514.82,0c512.199,0 931.245,-419.045 931.245,-931.244l-0,-2258.34c-0,-512.173 -419.046,-931.245 -931.245,-931.245\" style=\"fill:#46b3a1;fill-rule:nonzero;\"><\/path><path d=\"M2188.66,2804.59c-162.673,0 -294.572,-131.899 -294.572,-294.572l-0,-1575.79c-0,-162.673 131.899,-294.546 294.572,-294.546c162.673,-0 294.572,131.873 294.572,294.546l0,1575.79c0,162.673 -131.899,294.572 -294.572,294.572\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><path d=\"M2498.21,3365.67c-0,170.958 -138.596,309.555 -309.555,309.555c-170.959,-0 -309.555,-138.597 -309.555,-309.555c-0,-170.985 138.596,-309.555 309.555,-309.555c170.959,-0 309.555,138.57 309.555,309.555\" style=\"fill:#fff;fill-rule:nonzero;\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVotre solution de lancement d'alerte est-elle conforme ?\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-195c7b8 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"195c7b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"192\" data-end=\"424\">Lors de la s\u00e9lection d&rsquo;un syst\u00e8me, assurez-vous qu&rsquo;il r\u00e9pond \u00e0 toutes les exigences l\u00e9gales et qu&rsquo;il est conforme au RGPD. Il est essentiel que la solution que vous avez choisie comprenne les fonctions n\u00e9cessaires pour vous permettre de rester en conformit\u00e9 et de prot\u00e9ger la confidentialit\u00e9 des lanceurs d&rsquo;alerte.<\/p><p data-start=\"192\" data-end=\"424\">Nous avons compil\u00e9 une liste de contr\u00f4le des caract\u00e9ristiques cl\u00e9s pour vous aider \u00e0 choisir un fournisseur qui r\u00e9pond \u00e0 la fois \u00e0 <strong>la loi sur les lanceurs d&rsquo;alerte<\/strong> et aux <strong>normes RGPD<\/strong> &#8211; utilisez-la comme guide au cours de votre processus d&rsquo;approvisionnement .<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d94613d elementor-widget elementor-widget-image-gallery\" data-id=\"d94613d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-23614 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d94613d\" data-elementor-lightbox-title=\"Tabellbakgrund_FRENCH\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDQ1NzcsInVybCI6Imh0dHBzOlwvXC93d3cud2hpc3RsZWxpbmsuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8xMlwvVGFiZWxsYmFrZ3J1bmRfRlJFTkNILnBuZyIsInNsaWRlc2hvdyI6ImQ5NDYxM2QifQ%3D%3D\" href='https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH.png'><img decoding=\"async\" width=\"6984\" height=\"4167\" src=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH.png\" class=\"attachment-full size-full\" alt=\"Liste de contr\u00f4le pour la mise en place d&#039;un syst\u00e8me de lancement d&#039;alerte.\" srcset=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH.png 6984w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH-300x179.png 300w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH-1600x955.png 1600w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH-768x458.png 768w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH-1536x916.png 1536w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/12\/Tabellbakgrund_FRENCH-2048x1222.png 2048w\" sizes=\"(max-width: 6984px) 100vw, 6984px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57e01352 e-con-full e-flex e-con e-child\" data-id=\"57e01352\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fdbb313 e-con-full e-flex e-con e-child\" data-id=\"fdbb313\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63eec55 elementor-widget elementor-widget-jet-headline\" data-id=\"63eec55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">ASSUREZ VOTRE CONFORMIT\u00c9<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">\u00cates-vous pr\u00eats ?<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8842fa e-con-full e-flex e-con e-child\" data-id=\"a8842fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17f0314 elementor-widget__width-auto elementor-widget elementor-widget-jet-button\" data-id=\"17f0314\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-left hover-effect-0\" href=\"#contact-menu-anchor-fr\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__label\">Contacter<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__label\">Contacter<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d79030 elementor-widget__width-auto elementor-widget elementor-widget-jet-button\" data-id=\"3d79030\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-right hover-effect-0\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ2aW1lbyIsInVybCI6Imh0dHBzOlwvXC9wbGF5ZXIudmltZW8uY29tXC92aWRlb1wvNjkxNzc4OTYzP2g9ZDljNTk4MzI0MiN0PSJ9\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:serif=\"http:\/\/www.serif.com\/\" width=\"100%\" height=\"100%\" viewBox=\"0 0 1459 1459\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:2;\"><rect id=\"play-icon\" x=\"0\" y=\"0\" width=\"1458.33\" height=\"1458.33\" style=\"fill:none;\"><\/rect><clipPath id=\"_clip1\"><rect id=\"play-icon1\" serif:id=\"play-icon\" x=\"0\" y=\"0\" width=\"1458.33\" height=\"1458.33\"><\/rect><\/clipPath><g clip-path=\"url(#_clip1)\"><path d=\"M1435.84,729.167c-0,390.29 -316.378,706.668 -706.668,706.668c-390.291,-0 -706.668,-316.378 -706.668,-706.668c-0,-390.291 316.377,-706.668 706.668,-706.668c390.29,-0 706.668,316.377 706.668,706.668\" style=\"fill:#a5edd2;fill-rule:nonzero;\"><\/path><path d=\"M1458.33,729.167c0,-402.438 -326.728,-729.167 -729.166,-729.167c-402.438,-0 -729.167,326.729 -729.167,729.167c-0,402.438 326.729,729.166 729.167,729.166c402.438,0 729.166,-326.728 729.166,-729.166Zm-44.997,-0c0,377.603 -306.566,684.169 -684.169,684.169c-377.604,0 -684.17,-306.566 -684.17,-684.169c0,-377.604 306.566,-684.17 684.17,-684.17c377.603,0 684.169,306.566 684.169,684.17Z\" style=\"fill:#c5f3e2;\"><\/path><path d=\"M999.135,740.684l-374.776,235.292l0,-470.584l374.776,235.292Z\" style=\"fill:#5a4d4d;fill-rule:nonzero;\"><\/path><\/g><\/svg><\/span><span class=\"jet-button__label\">D\u00e9couvrez le fonctionnement<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__icon jet-elements-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:serif=\"http:\/\/www.serif.com\/\" width=\"100%\" height=\"100%\" viewBox=\"0 0 1459 1459\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:2;\"><rect id=\"play-icon\" x=\"0\" y=\"0\" width=\"1458.33\" height=\"1458.33\" style=\"fill:none;\"><\/rect><clipPath id=\"_clip1\"><rect id=\"play-icon1\" serif:id=\"play-icon\" x=\"0\" y=\"0\" width=\"1458.33\" height=\"1458.33\"><\/rect><\/clipPath><g clip-path=\"url(#_clip1)\"><path d=\"M1435.84,729.167c-0,390.29 -316.378,706.668 -706.668,706.668c-390.291,-0 -706.668,-316.378 -706.668,-706.668c-0,-390.291 316.377,-706.668 706.668,-706.668c390.29,-0 706.668,316.377 706.668,706.668\" style=\"fill:#a5edd2;fill-rule:nonzero;\"><\/path><path d=\"M1458.33,729.167c0,-402.438 -326.728,-729.167 -729.166,-729.167c-402.438,-0 -729.167,326.729 -729.167,729.167c-0,402.438 326.729,729.166 729.167,729.166c402.438,0 729.166,-326.728 729.166,-729.166Zm-44.997,-0c0,377.603 -306.566,684.169 -684.169,684.169c-377.604,0 -684.17,-306.566 -684.17,-684.169c0,-377.604 306.566,-684.17 684.17,-684.17c377.603,0 684.169,306.566 684.169,684.17Z\" style=\"fill:#c5f3e2;\"><\/path><path d=\"M999.135,740.684l-374.776,235.292l0,-470.584l374.776,235.292Z\" style=\"fill:#5a4d4d;fill-rule:nonzero;\"><\/path><\/g><\/svg><\/span><span class=\"jet-button__label\">D\u00e9couvrez le fonctionnement<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70076da e-con-full e-flex e-con e-child\" data-id=\"70076da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8eeefaf e-con-full e-flex e-con e-child\" data-id=\"8eeefaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e01d5e elementor-widget elementor-widget-jet-headline\" data-id=\"5e01d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Tout ce que vous aimeriez savoir et comment la directive vous affecte<\/span><\/span><span class=\"jet-headline__part jet-headline__second\"><span class=\"jet-headline__label\">Questions fr\u00e9quentes<\/span><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4443a92 elementor-widget elementor-widget-toggle\" data-id=\"4443a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7151\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7151\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Qu'est-ce que le lancement d'alerte ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7151\"><p>Il y a lancement d&rsquo;alerte lorsqu&rsquo;une personne soul\u00e8ve des inqui\u00e9tudes au sujet d&rsquo;actes r\u00e9pr\u00e9hensibles au sein d&rsquo;une organisation publique, priv\u00e9e ou gouvernementale. Il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;activit\u00e9s ill\u00e9gales, contraires \u00e0 l&rsquo;\u00e9thique ou nuisibles telles que la fraude, la corruption, l&rsquo;inconduite, le harc\u00e8lement, la discrimination ou les violations de la sant\u00e9, de la s\u00e9curit\u00e9 ou de l&rsquo;environnement.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7152\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7152\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quels sont les droits du lanceur d'alerte ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7152\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7152\"><p>Les lanceurs d&rsquo;alerte dans l&rsquo;UE sont prot\u00e9g\u00e9s contre toute forme de repr\u00e9sailles s&rsquo;ils signalent des violations du droit de l&rsquo;UE sur une s\u00e9rie de questions.<\/p><p>Il s&rsquo;agit notamment des violations relatives \u00e0\u00a0:<\/p><ul><li>Services financiers<\/li><li>Blanchiment d&rsquo;argent et financement du terrorisme<\/li><li>March\u00e9s publics<\/li><li>Sant\u00e9 publique<\/li><li>S\u00e9curit\u00e9 publique &#8211; produits, alimentation et transport<\/li><li>Protection de l&rsquo;environnement, radioprotection et s\u00fbret\u00e9 nucl\u00e9aire<\/li><li>Sant\u00e9 et bien-\u00eatre animal<\/li><li>Protection des consommateurs et des donn\u00e9es<\/li><li>S\u00e9curit\u00e9 des r\u00e9seaux et des syst\u00e8mes d&rsquo;information<\/li><\/ul><p>Un lanceur d&rsquo;alerte doit utiliser les canaux de signalement d\u00e9sign\u00e9s et croire que l&rsquo;information \u00e9tait vraie au moment du signalement.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7153\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7153\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que signifie la directive europ\u00e9enne pour les employeurs ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7153\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7153\"><p>La directive de l&rsquo;UE exige la mise en place de canaux de signalement efficaces et s\u00e9curis\u00e9s pour rendre possible le lancement d&rsquo;alerte interne.<\/p><p>Les organisations doivent s&rsquo;assurer que leurs canaux de signalement internes r\u00e9pondent \u00e0 des crit\u00e8res sp\u00e9cifiques. Cela inclut la facilit\u00e9 d&rsquo;acc\u00e8s, la propri\u00e9t\u00e9 et la gestion, la s\u00e9curit\u00e9, le RGPD et la mani\u00e8re dont les rapports sont cr\u00e9\u00e9s. En savoir plus sur l&rsquo;impact sur les entreprises.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7154\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-7154\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pourquoi y a-t-il une nouvelle directive europ\u00e9enne sur le lancement d'alerte ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7154\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-7154\"><p>L&rsquo;objectif est de lutter contre la corruption et d&rsquo;offrir une meilleure protection aux personnes qui signalent des fautes ou des infractions au droit de l&rsquo;Union.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7155\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-7155\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment nous conformons-nous \u00e0 la directive europ\u00e9enne sur le lancement d'alerte ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7155\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-7155\"><p>Vous aurez besoin de canaux de signalement s\u00e9curis\u00e9s en place. En d&rsquo;autres termes, un endroit s\u00fbr o\u00f9 vos employ\u00e9s et d&rsquo;autres personnes \u00e9troitement li\u00e9es \u00e0 votre entreprise peuvent signaler des comportements contraires \u00e0 l&rsquo;\u00e9thique.<\/p><p>Les canaux doivent r\u00e9pondre \u00e0 plusieurs exigences \u00e9nonc\u00e9es dans la directive, telles que garantir la confidentialit\u00e9, \u00eatre facilement accessibles et respecter les directives du RGPD.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7156\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-7156\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La directive europ\u00e9enne s'applique-t-elle \u00e0 toutes les entreprises ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7156\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-7156\"><p>La directive ne s&rsquo;applique qu&rsquo;aux organisations priv\u00e9es et publiques de l&rsquo;UE comptant plus de 50 employ\u00e9s.<\/p><p>De plus, les entreprises priv\u00e9es op\u00e9rant dans certains secteurs, tels que les services financiers ou celles vuln\u00e9rables au blanchiment d&rsquo;argent ou au financement du terrorisme, doivent se conformer.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7157\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-7157\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que se passe-t-il si les organisations ne se conforment pas \u00e0 la directive europ\u00e9enne sur le lancement d'alerte ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7157\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-7157\"><p>La directive europ\u00e9enne sur la protection des lanceurs d&rsquo;alerte ne fixe pas de sanctions minimales, mais elle exige que les versions nationales de la loi p\u00e9nalisent ceux qui emp\u00eachent les signalements, brisent la confidentialit\u00e9 ou exercent des repr\u00e9sailles contre les lanceurs d&rsquo;alerte.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7158\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-7158\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La directive s'applique-t-elle uniquement aux entreprises ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7158\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-7158\"><p>Non. Elle s&rsquo;applique \u00e9galement aux communes de l&rsquo;UE de plus de 10 000 habitants.<\/p><p>Cela s&rsquo;ajoute \u00e0 toute organisation, qu&rsquo;elle soit priv\u00e9e ou publique avec plus de 50 employ\u00e9s dans l&rsquo;UE.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Qu'est-ce que le lancement d'alerte ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Il y a lancement d&rsquo;alerte lorsqu&rsquo;une personne soul\\u00e8ve des inqui\\u00e9tudes au sujet d&rsquo;actes r\\u00e9pr\\u00e9hensibles au sein d&rsquo;une organisation publique, priv\\u00e9e ou gouvernementale. Il s&rsquo;agit g\\u00e9n\\u00e9ralement d&rsquo;activit\\u00e9s ill\\u00e9gales, contraires \\u00e0 l&rsquo;\\u00e9thique ou nuisibles telles que la fraude, la corruption, l&rsquo;inconduite, le harc\\u00e8lement, la discrimination ou les violations de la sant\\u00e9, de la s\\u00e9curit\\u00e9 ou de l&rsquo;environnement.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les droits du lanceur d'alerte ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Les lanceurs d&rsquo;alerte dans l&rsquo;UE sont prot\\u00e9g\\u00e9s contre toute forme de repr\\u00e9sailles s&rsquo;ils signalent des violations du droit de l&rsquo;UE sur une s\\u00e9rie de questions.<\\\/p><p>Il s&rsquo;agit notamment des violations relatives \\u00e0\\u00a0:<\\\/p><ul><li>Services financiers<\\\/li><li>Blanchiment d&rsquo;argent et financement du terrorisme<\\\/li><li>March\\u00e9s publics<\\\/li><li>Sant\\u00e9 publique<\\\/li><li>S\\u00e9curit\\u00e9 publique &#8211; produits, alimentation et transport<\\\/li><li>Protection de l&rsquo;environnement, radioprotection et s\\u00fbret\\u00e9 nucl\\u00e9aire<\\\/li><li>Sant\\u00e9 et bien-\\u00eatre animal<\\\/li><li>Protection des consommateurs et des donn\\u00e9es<\\\/li><li>S\\u00e9curit\\u00e9 des r\\u00e9seaux et des syst\\u00e8mes d&rsquo;information<\\\/li><\\\/ul><p>Un lanceur d&rsquo;alerte doit utiliser les canaux de signalement d\\u00e9sign\\u00e9s et croire que l&rsquo;information \\u00e9tait vraie au moment du signalement.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Que signifie la directive europ\\u00e9enne pour les employeurs ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La directive de l&rsquo;UE exige la mise en place de canaux de signalement efficaces et s\\u00e9curis\\u00e9s pour rendre possible le lancement d&rsquo;alerte interne.<\\\/p><p>Les organisations doivent s&rsquo;assurer que leurs canaux de signalement internes r\\u00e9pondent \\u00e0 des crit\\u00e8res sp\\u00e9cifiques. Cela inclut la facilit\\u00e9 d&rsquo;acc\\u00e8s, la propri\\u00e9t\\u00e9 et la gestion, la s\\u00e9curit\\u00e9, le RGPD et la mani\\u00e8re dont les rapports sont cr\\u00e9\\u00e9s. En savoir plus sur l&rsquo;impact sur les entreprises.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Pourquoi y a-t-il une nouvelle directive europ\\u00e9enne sur le lancement d'alerte ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>L&rsquo;objectif est de lutter contre la corruption et d&rsquo;offrir une meilleure protection aux personnes qui signalent des fautes ou des infractions au droit de l&rsquo;Union.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Comment nous conformons-nous \\u00e0 la directive europ\\u00e9enne sur le lancement d'alerte ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Vous aurez besoin de canaux de signalement s\\u00e9curis\\u00e9s en place. En d&rsquo;autres termes, un endroit s\\u00fbr o\\u00f9 vos employ\\u00e9s et d&rsquo;autres personnes \\u00e9troitement li\\u00e9es \\u00e0 votre entreprise peuvent signaler des comportements contraires \\u00e0 l&rsquo;\\u00e9thique.<\\\/p><p>Les canaux doivent r\\u00e9pondre \\u00e0 plusieurs exigences \\u00e9nonc\\u00e9es dans la directive, telles que garantir la confidentialit\\u00e9, \\u00eatre facilement accessibles et respecter les directives du RGPD.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"La directive europ\\u00e9enne s'applique-t-elle \\u00e0 toutes les entreprises ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La directive ne s&rsquo;applique qu&rsquo;aux organisations priv\\u00e9es et publiques de l&rsquo;UE comptant plus de 50 employ\\u00e9s.<\\\/p><p>De plus, les entreprises priv\\u00e9es op\\u00e9rant dans certains secteurs, tels que les services financiers ou celles vuln\\u00e9rables au blanchiment d&rsquo;argent ou au financement du terrorisme, doivent se conformer.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Que se passe-t-il si les organisations ne se conforment pas \\u00e0 la directive europ\\u00e9enne sur le lancement d'alerte ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>La directive europ\\u00e9enne sur la protection des lanceurs d&rsquo;alerte ne fixe pas de sanctions minimales, mais elle exige que les versions nationales de la loi p\\u00e9nalisent ceux qui emp\\u00eachent les signalements, brisent la confidentialit\\u00e9 ou exercent des repr\\u00e9sailles contre les lanceurs d&rsquo;alerte.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"La directive s'applique-t-elle uniquement aux entreprises ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Non. Elle s&rsquo;applique \\u00e9galement aux communes de l&rsquo;UE de plus de 10 000 habitants.<\\\/p><p>Cela s&rsquo;ajoute \\u00e0 toute organisation, qu&rsquo;elle soit priv\\u00e9e ou publique avec plus de 50 employ\\u00e9s dans l&rsquo;UE.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5481ba6c e-con-full e-flex e-con e-child\" data-id=\"5481ba6c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-87f6a15 e-con-full promotion-box e-flex e-con e-child\" data-id=\"87f6a15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c421d41 e-flex e-con-boxed e-con e-child\" data-id=\"c421d41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-910a8e6 elementor-widget elementor-widget-jet-headline\" data-id=\"910a8e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"jet-headline jet-headline--direction-vertical\"><span class=\"jet-headline__part jet-headline__first\"><span class=\"jet-headline__label\">Simplifiez les signalements internes<\/span><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c7fa0e e-con-full e-flex e-con e-child\" data-id=\"3c7fa0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6595df elementor-widget elementor-widget-image\" data-id=\"a6595df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/08\/Arianna_transp.png\" class=\"attachment-large size-large wp-image-110002\" alt=\"Arianna Tripodi, Territory Manager\" srcset=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/08\/Arianna_transp.png 300w, https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/08\/Arianna_transp-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b451829 e-flex e-con-boxed e-con e-child\" data-id=\"b451829\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca21de elementor-widget elementor-widget-heading\" data-id=\"1ca21de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Voyez comment cela fonctionne<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f6e39c elementor-widget elementor-widget-text-editor\" data-id=\"3f6e39c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9mo de 30 minutes \u2014 sans engagement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c31e1 elementor-widget__width-auto bookcall-france elementor-invisible elementor-widget elementor-widget-jet-button\" data-id=\"93c31e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"jet-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-button jet-elements\"><div class=\"jet-button__container\">\n\t<a class=\"jet-button__instance jet-button__instance--icon-left hover-effect-0\" href=\"#\" target=\"_blank\">\n\t\t<div class=\"jet-button__plane jet-button__plane-normal\"><\/div>\n\t\t<div class=\"jet-button__plane jet-button__plane-hover\"><\/div>\n\t\t<div class=\"jet-button__state jet-button__state-normal\">\n\t\t\t<span class=\"jet-button__label\">R\u00e9server une d\u00e9mo<\/span>\t\t<\/div>\n\t\t<div class=\"jet-button__state jet-button__state-hover\">\n\t\t\t<span class=\"jet-button__label\">R\u00e9server une d\u00e9mo<\/span>\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Directive sur le lancement d&rsquo;alerteComment se mettre en conformit\u00e9 avec les lois sur le lancement d&rsquo;alertes ? La directive europ\u00e9enne sur le lancement d&rsquo;alerte (2019\/1937) a \u00e9t\u00e9 introduite pour prot\u00e9ger les personnes qui signalent des fautes professionnelles. Cette r\u00e9glementation exige que les organisations mettent en place des syst\u00e8mes de signalement s\u00e9curis\u00e9s et confidentiels qui prot\u00e8gent [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_yoast_wpseo_focuskw":"Directive sur le lancement d'alerte","_yoast_wpseo_title":"Se conformer \u00e0 la directive et aux lois sur le lancement d\u2019alerte","_yoast_wpseo_metadesc":"Comment se conformer \u00e0 la directive sur le lancement d'alerte en France et en Belgique ? D\u00e9couvrez l'essentiel pour signaler les abus.","footnotes":""},"class_list":["post-23614","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Se conformer \u00e0 la directive et aux lois sur le lancement d\u2019alerte<\/title>\n<meta name=\"description\" content=\"Comment se conformer \u00e0 la directive sur le lancement d&#039;alerte en France et en Belgique ? D\u00e9couvrez l&#039;essentiel pour signaler les abus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurez votre conformit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Comment se conformer \u00e0 la directive sur le lancement d&#039;alerte en France et en Belgique ? D\u00e9couvrez l&#039;essentiel pour signaler les abus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/\" \/>\n<meta property=\"og:site_name\" content=\"Whistlelink\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/whistlelink\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:43:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/\",\"name\":\"Se conformer \u00e0 la directive et aux lois sur le lancement d\u2019alerte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/eu-directive-plane.png\",\"datePublished\":\"2022-01-19T09:26:59+00:00\",\"dateModified\":\"2026-09-01T09:43:37+00:00\",\"description\":\"Comment se conformer \u00e0 la directive sur le lancement d'alerte en France et en Belgique ? D\u00e9couvrez l'essentiel pour signaler les abus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/eu-directive-plane.png\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/eu-directive-plane.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/home-whistlelink-com-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assurez votre conformit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/\",\"name\":\"Whistlelink\",\"description\":\"Un fournisseur de confiance de solutions s\u00e9curis\u00e9es de signalement d'alertes.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/#organization\",\"name\":\"Whistlelink\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"width\":1200,\"height\":1200,\"caption\":\"Whistlelink\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/whistlelink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/whistlelink\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Whistlelink\"],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"name\":\"Annelie Demred\",\"contactType\":\"Territory Manager (CEO Whistlelink)\",\"telephone\":\"+46706838288\",\"email\":\"annelie.demred@whistlelink.com\",\"areaServed\":[\"EU\",\"Rest of the World\"],\"availableLanguage\":[\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Philipp Garz\",\"contactType\":\"Territory Manager\",\"telephone\":\"+498001816067\",\"email\":\"philipp.garz@whistlelink.com\",\"areaServed\":[\"Germany\",\"Austria\",\"Switzerland\",\"Sweden\"],\"availableLanguage\":[\"German\",\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Maria Boboc\",\"contactType\":\"Territory Manager\",\"telephone\":\"+34900752496\",\"email\":\"maria.boboc@whistlelink.com\",\"areaServed\":[\"United States\",\"Latin America\",\"Spain\",\"Romania\",\"Portugal\",\"Bulgaria\"],\"availableLanguage\":[\"Spanish\",\"Romanian\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Camilla Corsini\",\"contactType\":\"Territory Manager\",\"telephone\":\"+39800934277\",\"email\":\"camilla.corsini@whistlelink.com\",\"areaServed\":[\"Italy\",\"France\",\"Belgium\",\"Luxembourg\",\"Slovenia\",\"Serbia\",\"Croatia\",\"Greece\"],\"availableLanguage\":[\"Italian\",\"French\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Urszula Garbicz-Bry\u015b\",\"contactType\":\"Territory Manager\",\"telephone\":\"+48800005274\",\"email\":\"urszula.brys@whistlelink.com\",\"areaServed\":[\"Poland\",\"Czech Republic\",\"Slovakia\",\"Hungary\",\"Estonia\",\"Latvia\",\"Lithuania\"],\"availableLanguage\":[\"Polish\",\"English\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Se conformer \u00e0 la directive et aux lois sur le lancement d\u2019alerte","description":"Comment se conformer \u00e0 la directive sur le lancement d'alerte en France et en Belgique ? D\u00e9couvrez l'essentiel pour signaler les abus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/","og_locale":"fr_FR","og_type":"article","og_title":"Assurez votre conformit\u00e9","og_description":"Comment se conformer \u00e0 la directive sur le lancement d'alerte en France et en Belgique ? D\u00e9couvrez l'essentiel pour signaler les abus.","og_url":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/","og_site_name":"Whistlelink","article_publisher":"https:\/\/www.facebook.com\/whistlelink\/","article_modified_time":"2026-09-01T09:43:37+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/","url":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/","name":"Se conformer \u00e0 la directive et aux lois sur le lancement d\u2019alerte","isPartOf":{"@id":"https:\/\/www.whistlelink.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/#primaryimage"},"image":{"@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png","datePublished":"2022-01-19T09:26:59+00:00","dateModified":"2026-09-01T09:43:37+00:00","description":"Comment se conformer \u00e0 la directive sur le lancement d'alerte en France et en Belgique ? D\u00e9couvrez l'essentiel pour signaler les abus.","breadcrumb":{"@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/#primaryimage","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2022\/01\/eu-directive-plane.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.whistlelink.com\/fr\/se-mettre-en-conformite-directive-eu-lanceurs-alerte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.whistlelink.com\/fr\/home-whistlelink-com-fr\/"},{"@type":"ListItem","position":2,"name":"Assurez votre conformit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.whistlelink.com\/fr\/#website","url":"https:\/\/www.whistlelink.com\/fr\/","name":"Whistlelink","description":"Un fournisseur de confiance de solutions s\u00e9curis\u00e9es de signalement d'alertes.","publisher":{"@id":"https:\/\/www.whistlelink.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.whistlelink.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.whistlelink.com\/#organization","name":"Whistlelink","url":"https:\/\/www.whistlelink.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.whistlelink.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","width":1200,"height":1200,"caption":"Whistlelink"},"image":{"@id":"https:\/\/www.whistlelink.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/whistlelink\/","https:\/\/www.linkedin.com\/company\/whistlelink\/","https:\/\/www.youtube.com\/@Whistlelink"],"contactPoint":[{"@type":"ContactPoint","name":"Annelie Demred","contactType":"Territory Manager (CEO Whistlelink)","telephone":"+46706838288","email":"annelie.demred@whistlelink.com","areaServed":["EU","Rest of the World"],"availableLanguage":["Swedish","English"]},{"@type":"ContactPoint","name":"Philipp Garz","contactType":"Territory Manager","telephone":"+498001816067","email":"philipp.garz@whistlelink.com","areaServed":["Germany","Austria","Switzerland","Sweden"],"availableLanguage":["German","Swedish","English"]},{"@type":"ContactPoint","name":"Maria Boboc","contactType":"Territory Manager","telephone":"+34900752496","email":"maria.boboc@whistlelink.com","areaServed":["United States","Latin America","Spain","Romania","Portugal","Bulgaria"],"availableLanguage":["Spanish","Romanian","English"]},{"@type":"ContactPoint","name":"Camilla Corsini","contactType":"Territory Manager","telephone":"+39800934277","email":"camilla.corsini@whistlelink.com","areaServed":["Italy","France","Belgium","Luxembourg","Slovenia","Serbia","Croatia","Greece"],"availableLanguage":["Italian","French","English"]},{"@type":"ContactPoint","name":"Urszula Garbicz-Bry\u015b","contactType":"Territory Manager","telephone":"+48800005274","email":"urszula.brys@whistlelink.com","areaServed":["Poland","Czech Republic","Slovakia","Hungary","Estonia","Latvia","Lithuania"],"availableLanguage":["Polish","English"]}]}]}},"_links":{"self":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/pages\/23614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/comments?post=23614"}],"version-history":[{"count":44,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/pages\/23614\/revisions"}],"predecessor-version":[{"id":108070,"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/pages\/23614\/revisions\/108070"}],"wp:attachment":[{"href":"https:\/\/www.whistlelink.com\/fr\/wp-json\/wp\/v2\/media?parent=23614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}