{"id":56602,"date":"2023-09-07T07:01:53","date_gmt":"2023-09-07T06:01:53","guid":{"rendered":"https:\/\/www.whistlelink.com\/?post_type=blog&#038;p=56602"},"modified":"2023-09-19T07:27:06","modified_gmt":"2023-09-19T07:27:06","slug":"la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro","status":"publish","type":"blog","link":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/","title":{"rendered":"La nuova legge australiana impone l&#8217;eliminazione proattiva delle molestie sessuali sul posto di lavoro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il Respect at Work Bill, comunemente chiamato Respect@Work, \u00e8 un emendamento legislativo fondamentale per eliminare le molestie sessuali e la discriminazione basata sul sesso nei luoghi di lavoro australiani. Questa legge testimonia l&#8217;impegno dell&#8217;Australia a creare luoghi di lavoro pi\u00f9 sicuri, in cui i <a href=\"https:\/\/www.whistlelink.com\/it\/blog\/nove-modi-per-proteggere-i-dipendenti-dalle-molestie-sul-posto-di-lavoro\/\">dipendenti siano protetti<\/a> e le aziende siano ritenute responsabili di comportamenti illeciti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dal 12 dicembre 2023, le aziende australiane dovranno essere <em>proattive<\/em>, e non solo <em>reattive<\/em>, nella prevenzione delle molestie. Per conformarsi a queste nuove regole, la Commissione Australiana per i Diritti Umani (AHRC) ha pubblicato delle linee guida per aiutare le aziende ad adeguarsi ai cambiamenti.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contesto-del-progetto-di-legge-sul-rispetto-del-lavoro\">Contesto del progetto di legge sul rispetto del lavoro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2020, la Commissione Australiana per i Diritti Umani ha pubblicato il rapporto <a href=\"https:\/\/humanrights.gov.au\/our-work\/sex-discrimination\/publications\/respectwork-sexual-harassment-national-inquiry-report-2020\"><em>Respect@Work: National Inquiry into Sexual Harassment in Australian Workplaces<\/em><\/a>. L&#8217;indagine ha sottolineato la portata delle molestie sessuali nei luoghi di lavoro australiani. Sulla base di un&#8217;indagine nazionale, le conclusioni sono state crude:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il 33% dei lavoratori ha subito molestie sessuali negli ultimi cinque anni.<\/li>\n\n\n\n<li>4\/5 hanno subito molestie sessuali da parte di un uomo.<\/li>\n\n\n\n<li>Le giovani donne, di et\u00e0 compresa tra i 18 e i 29 anni, hanno avuto maggiori probabilit\u00e0 di subire molestie sessuali sul posto di lavoro.<\/li>\n\n\n\n<li>Il rischio di molestie \u00e8 aumentato in modo significativo per i gruppi gi\u00e0 emarginati: indigeni australiani, lavoratori disabili e persone identificate come LGBTI+.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In risposta ai risultati, l&#8217;AHRC ha stilato un elenco di raccomandazioni per eliminare i comportamenti che creano un ambiente di lavoro ostile basato sul sesso. Nel 2022, il governo australiano ha modificato la <em><a href=\"https:\/\/www.whistlelink.com\/it\/blog\/leggi-whistleblowing-nel-mondo\/\">legge sulla discriminazione sessuale<\/a> del 1984 <\/em>per rispondere a queste raccomandazioni.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quali-sono-i-punti-chiave-dell-emendamento\">Quali sono i punti chiave dell&#8217;emendamento?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c8 ora vietato sottoporre un&#8217;altra persona a un ambiente di lavoro ostile basato sul sesso.<\/li>\n\n\n\n<li>La soglia per le molestie basate sul sesso \u00e8 stata abbassata da &#8220;gravemente umiliante&#8221; a &#8220;umiliante&#8221;.<\/li>\n\n\n\n<li>La finestra temporale per la segnalazione di un presunto incidente \u00e8 stata estesa.&#8217;<\/li>\n<\/ul>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Soprattutto, il disegno di legge introduce un &#8220;dovere positivo&#8221; per tutti i datori di lavoro. In particolare:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le aziende devono adottare misure ragionevoli per eliminare i comportamenti illeciti sul posto di lavoro.<\/li>\n\n\n\n<li>Il dovere positivo \u00e8 preventivo piuttosto che reattivo. Le aziende possono essere ritenute responsabili per la mancata conformit\u00e0.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ampliare-le-tutele-per-i-lavoratori-australiani\">Ampliare le tutele per i lavoratori australiani<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le nuove leggi ampliano la copertura per proteggere i lavoratori australiani che conducono affari con o entrano in contatto con terzi. Le aziende, le ditte individuali e le organizzazioni devono ora adottare misure ragionevoli per <a href=\"https:\/\/www.whistlelink.com\/it\/blog\/proteggi-la-tua-azienda-in-8-semplici-passaggi-prima-parte\/\">eliminare comportamenti illeciti<\/a> da parte di clienti, collaboratori e figure in generale che entrano in contatto con i loro dipendenti, subappaltatori, lavoratori interinali, volontari e apprendisti in un contesto lavorativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebbene i requisiti dei doveri positivi possano sembrare ampi e persino impraticabili per le piccole imprese, le linee guida suggeriscono un certo grado di flessibilit\u00e0. Ci\u00f2 che \u00e8 realizzabile per una grande azienda pu\u00f2 non esserlo per un libero professionista o un piccolo imprenditore. Nel determinare le misure &#8220;proporzionate&#8221; o &#8220;ragionevoli&#8221; per eliminare le molestie, la Commissione considera le dimensioni, l&#8217;ubicazione e la natura di un&#8217;organizzazione. Inoltre, considera i fattori di rischio presenti all&#8217;interno dell&#8217;organizzazione. Un fast food che opera a tarda notte avr\u00e0 fattori di rischio molto diversi rispetto a un consulente aziendale online.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quali-misure-garantiranno-la-conformita\">Quali misure garantiranno la conformit\u00e0?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A partire dal 12 dicembre 2023, la Commissione Australiana per i Diritti Umani avr\u00e0 il potere di condurre indagini sulle organizzazioni che sospetta non aderiscano al dovere positivo. Potranno stipulare accordi giuridicamente vincolanti che specifichino le azioni che un&#8217;azienda deve intraprendere per garantire la conformit\u00e0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quali-sono-i-sette-standard-delle-linee-guida\">Quali sono i sette standard delle linee guida?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Commissione ha definito <a href=\"https:\/\/humanrights.gov.au\/sites\/default\/files\/2023-08\/Guidelines%20for%20Complying%20with%20the%20Positive%20Duty%20%282023%29.pdf\">sette standard<\/a> che tutte le aziende devono rispettare per soddisfare il loro dovere positivo. I meccanismi per affrontare ciascuno degli standard sono adattabili a ogni organizzazione. Mentre le imprese pi\u00f9 grandi possono dover implementare strumenti di segnalazione anonima, formazione delle risorse umane e campagne di sensibilizzazione dei dipendenti, alle piccole imprese sono consentite misure meno formali e costose per affrontare le molestie sessuali.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>Leadership: <\/strong>I<strong> <\/strong>leader devono esemplificare e impegnarsi in comportamenti che favoriscano l&#8217;inclusione sul posto di lavoro e l&#8217;uguaglianza di genere.<br><br><\/li>\n\n\n\n<li><strong>Cultura:<\/strong> Le aziende devono creare una cultura di trasparenza e sicurezza che incoraggi la denuncia delle molestie sessuali.<br><br><\/li>\n\n\n\n<li><strong>Conoscenza: <\/strong>Le<strong> <\/strong>linee guida e le politiche del luogo di lavoro devono essere chiarite per includere le aspettative comportamentali, le ripercussioni di una cattiva condotta e i diritti dei dipendenti. La formazione sul posto di lavoro pu\u00f2 essere appropriata per le organizzazioni pi\u00f9 grandi.<br><br><\/li>\n\n\n\n<li><strong>Gestione del rischio:<\/strong> \u00c8 necessario effettuare una valutazione dei rischi. \u00c8 necessario implementare strategie per ridurre e rispondere ai rischi.<br><br><\/li>\n\n\n\n<li><strong>Assistenza:<\/strong> Assistenza e risorse devono essere disponibili per i lavoratori che assistono o sono vittime di molestie sessuali.<br><br><\/li>\n\n\n\n<li><strong>Segnalazione e risposta:<\/strong> I dipendenti devono disporre di canali di segnalazione. Le risposte devono essere rapide e informate sul trauma per ridurre al minimo i danni.<br><br><\/li>\n\n\n\n<li><strong>Monitoraggio, valutazione e trasparenza:<\/strong> Le aziende devono monitorare i dati relativi alla cattiva condotta sul luogo di lavoro e valutarli per migliorare l&#8217;ambiente di lavoro.<br><\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-creare-un-ambiente-di-lavoro-piu-inclusivo\">Creare un ambiente di lavoro pi\u00f9 inclusivo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I sistemi di segnalazione anonima, come <a href=\"https:\/\/whistlelink.com\/\">Whistlelink<\/a> ed <a href=\"https:\/\/elker.com\/\">Elker<\/a>, sono strumenti fondamentali nella campagna per l&#8217;eliminazione delle molestie sessuali e della discriminazione sul posto di lavoro. Disporre di un canale confidenziale e anonimo per la segnalazione di episodi di cattiva condotta da parte dei dipendenti comporta notevoli vantaggi per l&#8217;azienda, quali:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Migliorare la felicit\u00e0 e la fidelizzazione dei dipendenti.<\/li>\n\n\n\n<li>Individuare precocemente i comportamenti scorretti.<\/li>\n\n\n\n<li>Ridurre al minimo il rischio di costosi contenziosi.<\/li>\n\n\n\n<li>Proteggere la privacy dei segnalanti.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 importante notare che questi <a href=\"https:\/\/www.whistlelink.com\/it\/blog\/vantaggi-rischi-nell-implementare-un-canale-whistleblowing\/\">sistemi di segnalazione anonima<\/a> sono parte integrante della cultura aziendale. Semplificano il processo di segnalazione e abbassano la soglia che consente ai dipendenti di avvertire i dirigenti di eventuali illeciti prima che diventino gravi incidenti pubblici. Il risultato non \u00e8 solo un luogo di lavoro pi\u00f9 sicuro. \u00c8 uno strato protettivo per l&#8217;integrit\u00e0 e la reputazione della vostra azienda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bio\">Bio:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Alex Murray \u00e8 un esperto di tecnologia e scrive regolarmente con il team di <a href=\"http:\/\/www.elker.com\">Elker<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volete saperne di pi\u00f9? Continuate a <a href=\"https:\/\/www.whistlelink.com\/fr\/blog\/\">leggere il nostro blog<\/a> per scoprire le ultime novit\u00e0 e le best practice aziendali!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Respect at Work Bill, comunemente chiamato Respect@Work, \u00e8 un emendamento legislativo fondamentale per eliminare le molestie sessuali e la discriminazione basata sul sesso nei luoghi di lavoro australiani. Questa legge testimonia l&#8217;impegno dell&#8217;Australia a creare luoghi di lavoro pi\u00f9 sicuri, in cui i dipendenti siano protetti e le aziende siano ritenute responsabili di comportamenti [&hellip;]<\/p>\n","protected":false},"featured_media":56580,"template":"","format":"standard","blog-category":[209,237],"class_list":["post-56602","blog","type-blog","status-publish","format-standard","has-post-thumbnail","hentry","blog-category-articoli","blog-category-notizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;eliminazione proattiva delle molestie sessuali in Australia<\/title>\n<meta name=\"description\" content=\"Il Respect at Work Bill \u00e8 una legge per l&#039;eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nuova legge australiana impone l&#039;eliminazione proattiva delle molestie sessuali sul posto di lavoro\" \/>\n<meta property=\"og:description\" content=\"Il Respect at Work Bill \u00e8 una legge per l&#039;eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Whistlelink\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/whistlelink\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T07:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2023\/08\/Elker-on-the-new-Australian-law.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/\",\"name\":\"L'eliminazione proattiva delle molestie sessuali in Australia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Elker-on-the-new-Australian-law.png\",\"datePublished\":\"2023-09-07T06:01:53+00:00\",\"dateModified\":\"2023-09-19T07:27:06+00:00\",\"description\":\"Il Respect at Work Bill \u00e8 una legge per l'eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Elker-on-the-new-Australian-law.png\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Elker-on-the-new-Australian-law.png\",\"width\":1200,\"height\":628,\"caption\":\"Elker on the new bill Respect at Work, Australia.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La nuova legge australiana impone l&#8217;eliminazione proattiva delle molestie sessuali sul posto di lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/\",\"name\":\"Whistlelink\",\"description\":\"Un fornitore affidabile di soluzioni sicure per il whistleblowing.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/#organization\",\"name\":\"Whistlelink\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"contentUrl\":\"https:\\\/\\\/www.whistlelink.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/wl_logo_vert_white_greysquare.svg\",\"width\":1200,\"height\":1200,\"caption\":\"Whistlelink\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whistlelink.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/whistlelink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/whistlelink\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Whistlelink\"],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"name\":\"Annelie Demred\",\"contactType\":\"Territory Manager (CEO Whistlelink)\",\"telephone\":\"+46706838288\",\"email\":\"annelie.demred@whistlelink.com\",\"areaServed\":[\"EU\",\"Rest of the World\"],\"availableLanguage\":[\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Philipp Garz\",\"contactType\":\"Territory Manager\",\"telephone\":\"+498001816067\",\"email\":\"philipp.garz@whistlelink.com\",\"areaServed\":[\"Germany\",\"Austria\",\"Switzerland\",\"Sweden\"],\"availableLanguage\":[\"German\",\"Swedish\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Maria Boboc\",\"contactType\":\"Territory Manager\",\"telephone\":\"+34900752496\",\"email\":\"maria.boboc@whistlelink.com\",\"areaServed\":[\"United States\",\"Latin America\",\"Spain\",\"Romania\",\"Portugal\",\"Bulgaria\"],\"availableLanguage\":[\"Spanish\",\"Romanian\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Camilla Corsini\",\"contactType\":\"Territory Manager\",\"telephone\":\"+39800934277\",\"email\":\"camilla.corsini@whistlelink.com\",\"areaServed\":[\"Italy\",\"France\",\"Belgium\",\"Luxembourg\",\"Slovenia\",\"Serbia\",\"Croatia\",\"Greece\"],\"availableLanguage\":[\"Italian\",\"French\",\"English\"]},{\"@type\":\"ContactPoint\",\"name\":\"Urszula Garbicz-Bry\u015b\",\"contactType\":\"Territory Manager\",\"telephone\":\"+48800005274\",\"email\":\"urszula.brys@whistlelink.com\",\"areaServed\":[\"Poland\",\"Czech Republic\",\"Slovakia\",\"Hungary\",\"Estonia\",\"Latvia\",\"Lithuania\"],\"availableLanguage\":[\"Polish\",\"English\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'eliminazione proattiva delle molestie sessuali in Australia","description":"Il Respect at Work Bill \u00e8 una legge per l'eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"La nuova legge australiana impone l'eliminazione proattiva delle molestie sessuali sul posto di lavoro","og_description":"Il Respect at Work Bill \u00e8 una legge per l'eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.","og_url":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/","og_site_name":"Whistlelink","article_publisher":"https:\/\/www.facebook.com\/whistlelink\/","article_modified_time":"2023-09-19T07:27:06+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2023\/08\/Elker-on-the-new-Australian-law.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/","url":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/","name":"L'eliminazione proattiva delle molestie sessuali in Australia","isPartOf":{"@id":"https:\/\/www.whistlelink.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/#primaryimage"},"image":{"@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2023\/08\/Elker-on-the-new-Australian-law.png","datePublished":"2023-09-07T06:01:53+00:00","dateModified":"2023-09-19T07:27:06+00:00","description":"Il Respect at Work Bill \u00e8 una legge per l'eliminazione proattiva delle molestie sessuali e delle discriminazioni sul sesso in Australia.","breadcrumb":{"@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/#primaryimage","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2023\/08\/Elker-on-the-new-Australian-law.png","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2023\/08\/Elker-on-the-new-Australian-law.png","width":1200,"height":628,"caption":"Elker on the new bill Respect at Work, Australia."},{"@type":"BreadcrumbList","@id":"https:\/\/www.whistlelink.com\/it\/blog\/la-nuova-legge-australiana-impone-leliminazione-proattiva-delle-molestie-sessuali-sul-posto-di-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.whistlelink.com\/it\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.whistlelink.com\/it\/blog\/"},{"@type":"ListItem","position":3,"name":"La nuova legge australiana impone l&#8217;eliminazione proattiva delle molestie sessuali sul posto di lavoro"}]},{"@type":"WebSite","@id":"https:\/\/www.whistlelink.com\/it\/#website","url":"https:\/\/www.whistlelink.com\/it\/","name":"Whistlelink","description":"Un fornitore affidabile di soluzioni sicure per il whistleblowing.","publisher":{"@id":"https:\/\/www.whistlelink.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.whistlelink.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.whistlelink.com\/#organization","name":"Whistlelink","url":"https:\/\/www.whistlelink.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.whistlelink.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","contentUrl":"https:\/\/www.whistlelink.com\/wp-content\/uploads\/2026\/07\/wl_logo_vert_white_greysquare.svg","width":1200,"height":1200,"caption":"Whistlelink"},"image":{"@id":"https:\/\/www.whistlelink.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/whistlelink\/","https:\/\/www.linkedin.com\/company\/whistlelink\/","https:\/\/www.youtube.com\/@Whistlelink"],"contactPoint":[{"@type":"ContactPoint","name":"Annelie Demred","contactType":"Territory Manager (CEO Whistlelink)","telephone":"+46706838288","email":"annelie.demred@whistlelink.com","areaServed":["EU","Rest of the World"],"availableLanguage":["Swedish","English"]},{"@type":"ContactPoint","name":"Philipp Garz","contactType":"Territory Manager","telephone":"+498001816067","email":"philipp.garz@whistlelink.com","areaServed":["Germany","Austria","Switzerland","Sweden"],"availableLanguage":["German","Swedish","English"]},{"@type":"ContactPoint","name":"Maria Boboc","contactType":"Territory Manager","telephone":"+34900752496","email":"maria.boboc@whistlelink.com","areaServed":["United States","Latin America","Spain","Romania","Portugal","Bulgaria"],"availableLanguage":["Spanish","Romanian","English"]},{"@type":"ContactPoint","name":"Camilla Corsini","contactType":"Territory Manager","telephone":"+39800934277","email":"camilla.corsini@whistlelink.com","areaServed":["Italy","France","Belgium","Luxembourg","Slovenia","Serbia","Croatia","Greece"],"availableLanguage":["Italian","French","English"]},{"@type":"ContactPoint","name":"Urszula Garbicz-Bry\u015b","contactType":"Territory Manager","telephone":"+48800005274","email":"urszula.brys@whistlelink.com","areaServed":["Poland","Czech Republic","Slovakia","Hungary","Estonia","Latvia","Lithuania"],"availableLanguage":["Polish","English"]}]}]}},"_links":{"self":[{"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/blog\/56602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":7,"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/blog\/56602\/revisions"}],"predecessor-version":[{"id":56893,"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/blog\/56602\/revisions\/56893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/media\/56580"}],"wp:attachment":[{"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/media?parent=56602"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/www.whistlelink.com\/it\/wp-json\/wp\/v2\/blog-category?post=56602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}